{"id":564,"date":"2011-09-25T13:24:04","date_gmt":"2011-09-25T18:24:04","guid":{"rendered":"http:\/\/programasperu.com\/restaurantes-peruanos\/?p=564"},"modified":"2021-04-19T14:17:50","modified_gmt":"2021-04-19T19:17:50","slug":"sacsayhuaman","status":"publish","type":"post","link":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/564\/sacsayhuaman.html","title":{"rendered":"Sacsayhuaman"},"content":{"rendered":"<p><a href=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/11953175221.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-6255\" title=\"1195317522\" alt=\"\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/11953175221-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/11953175221-300x199.jpg 300w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/11953175221.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div><strong>Rese\u00f1a:<\/strong><\/div>\n<ul>\n<li>Nuestro principal objetivo es satisfacer las expectativas de nuestros clientes, brindando una atenci\u00f3n de calidad, previniendo la contaminaci\u00f3n generada en nuestras actividades y alcanzando la mejora continua de nuestros procesos.<\/li>\n<li>Atenci\u00f3n esmerada durante las 24 horas del d\u00eda. En nuestro Restaurante podr\u00e1 disfrutar de la gran variedad de platos que posee la gastronom\u00eda peruana al igual que platos de corte internacional cuidadosamente elaborados por nuestro chef.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/costadesol-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1463 aligncenter\" title=\"costadesol\" alt=\"\" src=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/costadesol-1-300x134.jpg\" width=\"300\" height=\"134\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/costadesol-1-300x134.jpg 300w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/costadesol-1.jpg 982w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div><strong>Direcci\u00f3n:<\/strong><\/div>\n<ul>\n<li>Aeropuerto Internacional Jorge Ch\u00e1vez Av. Elmer Faucett s\/n &#8211; Callao<\/li>\n<\/ul>\n<div><strong>Horario:<\/strong><\/div>\n<ul>\n<li>24 horas al d\u00eda<\/li>\n<\/ul>\n<div><strong>Fono:<\/strong><\/div>\n<ul>\n<li><a href=\"tel:017112000\" target=\"_blank\" rel=\"noopener\">(01)7112000<\/a><\/li>\n<\/ul>\n<div><strong>Web:<\/strong><\/div>\n<ul>\n<li><a href=\"https:\/\/www.costadelsolperu.com\/hoteles\/hotel-costa-del-sol-wyndham-lima-ciudad\/\" target=\"_blank\" rel=\"noopener\">Costa del Sol<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Rese\u00f1a: Nuestro principal objetivo es satisfacer las expectativas de nuestros clientes, brindando una atenci\u00f3n de calidad, previniendo la contaminaci\u00f3n generada en nuestras actividades y alcanzando la mejora continua de nuestros procesos. Atenci\u00f3n esmerada durante las 24 horas del d\u00eda. En &hellip; <a href=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/564\/sacsayhuaman.html\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[210],"class_list":{"0":"post-564","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-comida-internacional"},"_links":{"self":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":0,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media?parent=564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/categories?post=564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/tags?post=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}