{"id":392,"date":"2011-09-25T12:09:37","date_gmt":"2011-09-25T17:09:37","guid":{"rendered":"http:\/\/programasperu.com\/restaurantes-peruanos\/?p=392"},"modified":"2021-04-15T18:06:24","modified_gmt":"2021-04-15T23:06:24","slug":"la-bonbonniere","status":"publish","type":"post","link":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/392\/la-bonbonniere.html","title":{"rendered":"La Bonbonniere"},"content":{"rendered":"<div><strong>Rese\u00f1a:<\/strong><\/div>\n<ul>\n<li>La Bonbonniere le da la bienvenida a su nueva ventana y espera que sea del agrado de todos sus visitantes, en esta nueva etapa esperamos estar mucho mas cerca a todos ustedes, que son la raz\u00f3n de nuestro existir.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/bl-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2094 aligncenter\" title=\"bl\" src=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/bl-1-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/bl-1-300x135.jpg 300w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/bl-1-1024x463.jpg 1024w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/bl-1.jpg 1139w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div><strong>Especialidades:<\/strong><\/div>\n<ul>\n<li>Menu del d\u00eda, La hora del t\u00e9, Pasteler\u00eda.<\/li>\n<\/ul>\n<div><strong>Direcciones:<\/strong><\/div>\n<ul>\n<li>Ca. Burgos 415 &#8211; San Isidro<br \/>\n<a href=\"tel:(01)4212447\">(01)4212447<\/a><br \/>\n<a href=\"mailto:admin@labonbonniere.com.pe\">admin@labonbonniere.com.pe<\/a><br \/>\nMar a Dom: 8am &#8211; 11pm<\/li>\n<li>C.C. Jockey Plaza &#8211; Surco<br \/>\n<a href=\"tel:(01)4371964\">(01)4371964<\/a><br \/>\n<a href=\"mailto:jockey@bonperu.com\">jockey@bonperu.com<\/a><br \/>\nLun a Dom: 9am &#8211; 11pm<\/li>\n<li>C.C. Larcomar &#8211; Miraflores<br \/>\n<a href=\"tel:(01)4472267\">(01)4472267<\/a><br \/>\n<a href=\"mailto:larcomar@bonperu.com\">larcomar@bonperu.com<\/a><br \/>\nLun a Dom: 9am &#8211; 11pm<\/li>\n<li>Aeropuerto Internacional Jorge Ch\u00e1vez &#8211; Callao<br \/>\n<a href=\"tel:(9)81133346\">(9)81133346<\/a><br \/>\n<a href=\"mailto:aeropuerto@bonperu.com\">aeropuerto@bonperu.com<\/a><br \/>\nLun a Dom: 24 horas<\/li>\n<\/ul>\n<div><strong>Web:<\/strong><\/div>\n<ul>\n<li><\/li>\n<li><a href=\"https:\/\/www.facebook.com\/Bonbonniere.peru\">Facebook<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Rese\u00f1a: La Bonbonniere le da la bienvenida a su nueva ventana y espera que sea del agrado de todos sus visitantes, en esta nueva etapa esperamos estar mucho mas cerca a todos ustedes, que son la raz\u00f3n de nuestro existir. &hellip; <a href=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/392\/la-bonbonniere.html\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[55,82],"tags":[1023,1022,696],"class_list":{"0":"post-392","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-carnes-y-parrillas","8":"category-pescados-y-mariscos","9":"tag-la-hora-del-te","10":"tag-menu-del-dia","11":"tag-pasteleria"},"_links":{"self":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/comments?post=392"}],"version-history":[{"count":0,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media\/2094"}],"wp:attachment":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media?parent=392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/categories?post=392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/tags?post=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}