{"id":2950,"date":"2012-02-09T22:20:19","date_gmt":"2012-02-10T03:20:19","guid":{"rendered":"http:\/\/programasperu.com\/restaurantes-peruanos\/?p=2950"},"modified":"2019-02-20T23:48:39","modified_gmt":"2019-02-21T04:48:39","slug":"chifa-fong-mey","status":"publish","type":"post","link":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/2950\/chifa-fong-mey.html","title":{"rendered":"Chifa Fong Mey"},"content":{"rendered":"<div><a href=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-logo.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10056\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-logo.png\" alt=\"fong-mey-logo\" width=\"198\" height=\"74\" \/><\/a><\/div>\n<div><strong>Rese\u00f1a:<\/strong><\/div>\n<ul>\n<li>En nuestros locales encontrara gran variedad de platos gourmet de la comida china, preparados por expertos cocineros Cantoneses que preparan potajes con productos 100% naturales y bajos en grasas supervisados por expertos.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-chifa.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10055\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-chifa.png\" alt=\"fong-mey-chifa\" width=\"165\" height=\"124\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-salon.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10057\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/fong-mey-salon.png\" alt=\"fong-mey-salon\" width=\"165\" height=\"124\" \/><\/a><\/p>\n<div><strong style=\"text-align: center;\">Especialidades:<\/strong><\/div>\n<ul>\n<li>Costillas de Cerdo dulce, Gallina al vapor con hongos chinos, Pescado al vapor entero, Camarones cristal, Pato a la laguna, Sei si ha, Pa chi kay, Lo hon chay.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10054\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/chifa-fong-mey.png\" alt=\"chifa-fong-mey\" width=\"239\" height=\"320\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/chifa-fong-mey.png 239w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/chifa-fong-mey-224x300.png 224w\" sizes=\"auto, (max-width: 239px) 100vw, 239px\" \/><\/p>\n<div><strong>Direcci\u00f3n:<\/strong><\/div>\n<ul>\n<li>Urb. Magisterial II B-3 Yanahuara (Frente al Ovalo\u00a0Qui\u00f1ones), Arequipa<\/li>\n<\/ul>\n<div><strong>Fonos:<\/strong><\/div>\n<ul>\n<li><a href=\"tel:054258445\">(054)258445<\/a><\/li>\n<li><a href=\"tel:054272843\">(054)272843<\/a><\/li>\n<\/ul>\n<div><strong>Web:<\/strong><\/div>\n<ul>\n<li><a href=\"https:\/\/www.aiyellow.com\/fongmey\/\">P\u00e1ginas Amarillas<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Rese\u00f1a: En nuestros locales encontrara gran variedad de platos gourmet de la comida china, preparados por expertos cocineros Cantoneses que preparan potajes con productos 100% naturales y bajos en grasas supervisados por expertos. Especialidades: Costillas de Cerdo dulce, Gallina al &hellip; <a href=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/2950\/chifa-fong-mey.html\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[177,95,29,31],"tags":[279,197],"class_list":{"0":"post-2950","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bar","8":"category-buffet-disponible","9":"category-cafe","10":"category-chifa","11":"tag-buffets","12":"tag-chifa-2"},"_links":{"self":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/2950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/comments?post=2950"}],"version-history":[{"count":0,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/2950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media\/10055"}],"wp:attachment":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media?parent=2950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/categories?post=2950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/tags?post=2950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}