{"id":217,"date":"2011-09-25T10:20:05","date_gmt":"2011-09-25T15:20:05","guid":{"rendered":"http:\/\/programasperu.com\/restaurantes-peruanos\/?p=217"},"modified":"2021-04-19T13:42:53","modified_gmt":"2021-04-19T18:42:53","slug":"cafe-colombia","status":"publish","type":"post","link":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/217\/cafe-colombia.html","title":{"rendered":"Cafe Colombia"},"content":{"rendered":"<p><strong>Rese\u00f1a:<\/strong><\/p>\n<ul>\n<li>Nuestro Caf\u00e9 est\u00e1 localizado en el hermoso y moderno distrito de Miraflores en la ciudad de Lima, lugar accesible y c\u00e9ntrico donde podr\u00e1 disfrutar de nuestra variada carta y eventos musicales como si estuviera en nuestro pa\u00eds.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/fotocaf\u00e9colombia-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1021\" title=\"fotocaf\u00e9colombia\" alt=\"\" src=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/fotocaf\u00e9colombia-1-300x138.jpg\" width=\"300\" height=\"138\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/fotocaf\u00e9colombia-1-300x138.jpg 300w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/fotocaf\u00e9colombia-1.jpg 574w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Especialidades:<br \/>\n<\/strong><\/p>\n<ul>\n<li>Desayuno, Almuerzo, Cena, Caf\u00e9 y Bebidas.<\/li>\n<\/ul>\n<p><strong>Direcci\u00f3n:<\/strong><\/p>\n<ul>\n<li>Av. La Paz 646 Interior 19 &#8211; Pasaje El Suche, Miraflores<\/li>\n<\/ul>\n<p><strong>Horarios:<\/strong><\/p>\n<ul>\n<li>Lunes: 4:30pm &#8211; 11pm<\/li>\n<li>Martes y Mi\u00e9rcoles: 10am &#8211; 11pm<\/li>\n<li>Viernes y S\u00e1bado: 10am &#8211; 3pm<\/li>\n<li>Domingo: 1pm &#8211; 6pm<\/li>\n<\/ul>\n<p><strong>Fonos<\/strong>:<\/p>\n<ul>\n<li><a href=\"tel:012430285\">(01)2430285<\/a><\/li>\n<li><a href=\"tel:999200860\">(9)99200860<\/a><\/li>\n<\/ul>\n<p><strong>Web:<\/strong><\/p>\n<p><strong>Correo:<\/strong><\/p>\n<ul>\n<li><a href=\"mailto:ventas@cafecolombiaperu.com\">ventas@cafecolombiaperu.com<\/a><\/li>\n<\/ul>\n<p><strong>Ubicaci\u00f3n:<\/strong><br \/>\n<a href=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/caf\u00e9colombia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1020\" title=\"caf\u00e9colombia\" alt=\"\" src=\"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/caf\u00e9colombia-300x222.png\" width=\"300\" height=\"222\" srcset=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/caf\u00e9colombia-300x222.png 300w, https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2011\/09\/caf\u00e9colombia.png 588w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rese\u00f1a: Nuestro Caf\u00e9 est\u00e1 localizado en el hermoso y moderno distrito de Miraflores en la ciudad de Lima, lugar accesible y c\u00e9ntrico donde podr\u00e1 disfrutar de nuestra variada carta y eventos musicales como si estuviera en nuestro pa\u00eds. Especialidades: Desayuno, &hellip; <a href=\"https:\/\/www.programasperu.com\/restaurantes-peruanos\/217\/cafe-colombia.html\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[177,29],"tags":[204,207,7,206,205],"class_list":{"0":"post-217","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bar","8":"category-cafe","9":"tag-cafe-2","10":"tag-cafe-colombiano","11":"tag-cafeteria","12":"tag-colombia","13":"tag-miraflores"},"_links":{"self":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/comments?post=217"}],"version-history":[{"count":0,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/posts\/217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media\/1020"}],"wp:attachment":[{"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media?parent=217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/categories?post=217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/tags?post=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}