{"id":2824,"date":"2012-02-07T18:00:09","date_gmt":"2012-02-07T23:00:09","guid":{"rendered":"http:\/\/programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F.jpg"},"modified":"2012-02-07T18:00:09","modified_gmt":"2012-02-07T23:00:09","slug":"f-2","status":"inherit","type":"attachment","link":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/2822\/2822.html\/f-2","title":{"rendered":"F"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-2824","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F-300x225.jpg 300w, http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"720","height":"540","hwstring_small":"height='96' width='128'","file":"2012\/02\/F.jpg","sizes":{"thumbnail":{"file":"F-150x150.jpg","width":"150","height":"150","ewww_image_optimizer":"No savings","source_url":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F-150x150.jpg"},"medium":{"file":"F-300x225.jpg","width":"300","height":"225","ewww_image_optimizer":"No savings","source_url":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F-300x225.jpg"},"post-thumbnail":{"file":"F-720x350.jpg","width":"720","height":"350","ewww_image_optimizer":"No savings","source_url":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F-720x350.jpg"},"full":{"file":"F.jpg","width":720,"height":540,"mime_type":"image\/jpeg","source_url":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""},"ewww_image_optimizer":"No savings"},"post":2822,"source_url":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-content\/uploads\/2012\/02\/F.jpg","_links":{"self":[{"href":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media\/2824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.programasperu.com\/restaurantes-peruanos\/wp-json\/wp\/v2\/comments?post=2824"}]}}